{"id":51701,"date":"2018-04-13T21:27:29","date_gmt":"2018-04-13T21:27:29","guid":{"rendered":"https:\/\/dev.conube.com.br\/?p=51701"},"modified":"2025-01-28T16:55:18","modified_gmt":"2025-01-28T19:55:18","slug":"o-que-e-contribuicao-sindical-patronal","status":"publish","type":"post","link":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/","title":{"rendered":"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Minha empresa \u00e9 obrigada a pagar?"},"content":{"rendered":"<p>Voc\u00ea sabe qual a import\u00e2ncia de conhecer o conceito de\u00a0Contribui\u00e7\u00e3o Sindical Patronal? No que o seu pagamento pode impactar sua empresa? Entenda tudo sobre essa contribui\u00e7\u00e3o e tamb\u00e9m descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 contribui\u00e7\u00e3o sindical patronal.<\/p>\n<h2>O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal?<\/h2>\n<p>A Contribui\u00e7\u00e3o Sindical Patronal \u00e9 uma forma de Contribui\u00e7\u00e3o Social prevista na Constitui\u00e7\u00e3o Federal Brasileira e na <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/Del5452.htm\" target=\"_blank\" rel=\"noopener noreferrer\">CLT (Consolida\u00e7\u00e3o das Leis do Trabalho)<\/a>. Atrav\u00e9s dela, o pagamento \u00e9 atribu\u00eddo aos empregadores em benef\u00edcio das entidades de classe representativas de seus funcion\u00e1rios.<\/p>\n<h2>Quem deve pagar essa Contribui\u00e7\u00e3o?<\/h2>\n<p>Em tese, todas as empresas devem realizar os pagamentos. As exce\u00e7\u00f5es s\u00e3o:<\/p>\n<p>\u2022 Empresas sem empregados<br \/>\n\u2022 Empresas optantes pelo <a href=\"\/blog\/mudancas-no-simples-nacional\/\">Simples Nacional<\/a> (devem consultar o Minist\u00e9rio do Trabalho sobre o assunto, uma vez que alguns Sindicatos t\u00eam conseguido exig\u00eancia de pagamento para essas empresas, mas a grande maioria est\u00e1 isenta)<br \/>\n\u2022 Condom\u00ednios e Entidades sem fins lucrativos (desde que a tenha declarado na RAIS \u2013 Rela\u00e7\u00e3o Anual de Informa\u00e7\u00f5es Anuais \u2013 Portaria MTE 1.012\/03)<\/p>\n<p>Importante ressaltar que as empresas que estejam com suas atividades paralisadas, mas ainda sem a formaliza\u00e7\u00e3o do encerramento, tamb\u00e9m devem efetuar o pagamento.<\/p>\n<p><a href=\"https:\/\/www.conube.com.br\/trocar-contador\/?utm_source=blog&amp;utm_medium=cta&amp;utm_campaign=site-trocar-contador-v2\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-55572 size-full\" src=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2024\/10\/Site-Trocar-Contador-v2.png\" alt=\"o-que-e-contribuicao-sindical-patronal\" width=\"700\" height=\"330\" srcset=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2024\/10\/Site-Trocar-Contador-v2.png 700w, https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2024\/10\/Site-Trocar-Contador-v2-300x141.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<h2>O que muda com a Reforma Trabalhista?<\/h2>\n<p>A princ\u00edpio, todas as empresas empregadoras de m\u00e3o de obra devem efetuar o pagamento da Contribui\u00e7\u00e3o. No entanto, com a nova <a href=\"\/blog\/o-que-muda-com-a-reforma-trabalhista\/\">Reforma Trabalhista<\/a>, formalizada pela <a href=\"http:\/\/www.normaslegais.com.br\/legislacao\/Lei-13467-2017.htm\" target=\"_blank\" rel=\"noopener noreferrer\">Lei 13.467<\/a> de 13 de julho de 2017, houve uma sens\u00edvel mudan\u00e7a. Isso em todo o funcionamento e mecanismo dos Sindicatos. A maior delas foi a mudan\u00e7a que tornou a Contribui\u00e7\u00e3o Sindical Patronal opcional. Com essa altera\u00e7\u00e3o, foi dada a liberdade de escolha \u00e0s empresas para decidir pelo pagamento ou n\u00e3o.<\/p>\n<p>Assim, os Sindicatos somente poder\u00e3o efetuar as cobran\u00e7as \u00e0quelas empresas que manifestarem expressamente a inten\u00e7\u00e3o de pagar. Ou seja, uma empresa deve informar ao Sindicato seu interesse. Ao contr\u00e1rio do que ocorria antes, quando as empresas que queriam isen\u00e7\u00e3o da cobran\u00e7a \u00e9 que tinham que enviar uma carta se opondo ao pagamento.<\/p>\n<p>Um ponto a ser destacado \u00e9 com rela\u00e7\u00e3o \u00e0s empresas \u201cassociadas\u201d aos Sindicatos, cujo pagamento ainda obrigat\u00f3rio. Somente as empresas filiadas t\u00eam o pagamento facultativo.<\/p>\n<h2>Sindicatos pedem obrigatoriedade<\/h2>\n<p>J\u00e1 existem algumas a\u00e7\u00f5es judiciais que est\u00e3o dando ganho de causa aos Sindicatos que pedem a obrigatoriedade do pagamento. Isso n\u00e3o s\u00f3 das empresas associadas. Contudo, como ainda n\u00e3o existe um posicionamento firmado pelos Tribunais Superiores ou uma decis\u00e3o final a respeito do assunto, o que deve ser levado em considera\u00e7\u00e3o \u00e9 o que estipula a legisla\u00e7\u00e3o, que confere \u00e0s empresas a escolha pelo pagamento, em conformidade com a previs\u00e3o da nova reda\u00e7\u00e3o dos arts. 578 e 579 da CLT.<\/p>\n<p><em>\u201cArt. 578. As contribui\u00e7\u00f5es devidas aos sindicatos pelos participantes das categorias econ\u00f4micas ou profissionais ou das profiss\u00f5es liberais representadas pelas referidas entidades ser\u00e3o, sob a denomina\u00e7\u00e3o de contribui\u00e7\u00e3o sindical, pagas, recolhidas e aplicadas na forma estabelecida neste Cap\u00edtulo, desde que pr\u00e9via e expressamente autorizadas.\u201d<\/em><\/p>\n<p><em>\u201cArt. 579. O desconto da contribui\u00e7\u00e3o sindical est\u00e1 condicionado \u00e0 autoriza\u00e7\u00e3o pr\u00e9via e expressa dos que participem de uma determinada categoria econ\u00f4mica ou profissional, ou de uma profiss\u00e3o liberal, em favor do sindicato representativo da mesma categoria\u201d.<\/em><\/p>\n<p>Assim, a melhor orienta\u00e7\u00e3o a ser dada ao caso \u00e9 de que deve o empregador ficar atento e acompanhar o desenvolvimento do assunto. Principalmente no que se refere \u00e0s decis\u00f5es judiciais e o que tem sido dito e entendido pelos legisladores.<\/p>\n<h2>Conven\u00e7\u00e3o ou Acordo Coletivo de Trabalho<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-56066\" src=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Imagem-interna-O-que-e-Contribuicao-Sindical-Patronal.png\" alt=\"o-que-e-contribuicao-sindical-patronal\" width=\"1280\" height=\"520\" srcset=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Imagem-interna-O-que-e-Contribuicao-Sindical-Patronal.png 1280w, https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Imagem-interna-O-que-e-Contribuicao-Sindical-Patronal-300x122.png 300w, https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Imagem-interna-O-que-e-Contribuicao-Sindical-Patronal-1024x416.png 1024w, https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Imagem-interna-O-que-e-Contribuicao-Sindical-Patronal-768x312.png 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p>Outra\u00a0pergunta que tem surgido muito \u00e9 com rela\u00e7\u00e3o a exist\u00eancia de obrigatoriedade de pagamento da Contribui\u00e7\u00e3o Sindical Patronal nas Conven\u00e7\u00f5es ou Acordos Coletivos de Trabalho. E a resposta para esta d\u00favida \u00e9 que \u201cn\u00e3o\u201d \u00e9 obrigat\u00f3rio, uma vez que existem in\u00fameros entendimentos de que as Conven\u00e7\u00f5es ou Acordos Coletivos n\u00e3o t\u00eam autoridade para tratar ou estipular normas acerca da mat\u00e9ria. Portanto, as empresas n\u00e3o associadas aos Sindicatos podem, sim, optar pelo pagamento ou n\u00e3o da Contribui\u00e7\u00e3o Sindical Patronal, conforme sua avalia\u00e7\u00e3o.<\/p>\n<h2>Quando s\u00e3o realizados os pagamentos?<\/h2>\n<p>A Contribui\u00e7\u00e3o Sindical Patronal \u00e9 recolhida anualmente e deve ser paga at\u00e9 o \u00faltimo dia do m\u00eas de janeiro. As empresas constitu\u00eddas ap\u00f3s janeiro do ano corrente devem pagar a Contribui\u00e7\u00e3o caso estejam obrigadas ou optar pelo pagamento no m\u00eas de requerimento do registro ou da licen\u00e7a para exercer a atividade.<\/p>\n<h2>Como \u00e9 realizado o c\u00e1lculo?<\/h2>\n<p>O c\u00e1lculo \u00e9 definido pelos Sindicatos que tomam como base o capital social da empresa, mediante aplica\u00e7\u00e3o da mesmo na Tabela apresentada no art. 580, inciso III da CLT. Quando a empresa possuir filiais, sucursais ou ag\u00eancias na mesma base territorial da matriz, pertencentes ao mesmo Sindicato, somente a matriz far\u00e1 os pagamentos (entende-se como base territorial, a \u00e1rea geogr\u00e1fica onde se situa a categoria econ\u00f4mica ou profissional representada pelo Sindicato).<\/p>\n<p>Quando as filiais, sucursais ou ag\u00eancias forem em bases territoriais diferentes, entende-se que deve ser calculada a propor\u00e7\u00e3o do capital social da matriz correspondente \u00e0 cada filial, sucursal ou ag\u00eancia e cada uma delas paga diretamente aos respectivos sindicatos. Ou seja, deve-se\u00a0calcular a propor\u00e7\u00e3o percentual que cada unidade possui, tomando como base o capital social da matriz da empresa e aplicar o resultado \u00e1 tabela do art. 580, inciso III da CLT, para verifica\u00e7\u00e3o do valor a ser pago ao Sindicato.<\/p>\n<h2>O que \u00e9 feito com o valor da Contribui\u00e7\u00e3o?<\/h2>\n<p>Al\u00e9m de entender o que \u00e9 Contribui\u00e7\u00e3o Sindical, \u00e9 necess\u00e1rio saber para onde vai essa contribui\u00e7\u00e3o. Em resumo, o valor repassado aos Sindicatos e toda a sua estrutura funcional, como federa\u00e7\u00f5es, confedera\u00e7\u00f5es e centrais sindicais, \u00e9 utilizado para que os mesmos realizem a representatividade dos interesses dos funcion\u00e1rios e empresas, buscando benef\u00edcios e melhores condi\u00e7\u00f5es de trabalho e produ\u00e7\u00e3o.<\/p>\n<p>Quando se fala em vantagens e desvantagens, com a nova legisla\u00e7\u00e3o trabalhista, que alterou as condi\u00e7\u00f5es e obrigatoriedade para a realiza\u00e7\u00e3o dos pagamentos, muito se tem falado que haver\u00e1 uma maior representatividade dos Sindicatos, que buscar\u00e1 estruturar e intensificar suas atividades com maior apresenta\u00e7\u00e3o de resultados e benef\u00edcios.<\/p>\n<p>Com a mudan\u00e7a na receita sindical, uma retirada imediata, por anos recebida, ir\u00e1 comprometer consideravelmente os compromissos financeiros assumidos. Bem como o pagamento de trabalhadores que prestam servi\u00e7os nestes Sindicatos.\u00a0Valores anteriormente recebidos agora somente poder\u00e3o ser cobrados com a concord\u00e2ncia dos integrantes da categoria.<\/p>\n<h2>Caracter\u00edsticas<\/h2>\n<p>A receita dos pagamentos da Contribui\u00e7\u00e3o Sindical Patronal realizados pelas empresas \u00e9 recebida pela Caixa Econ\u00f4mica Federal, que \u00e9 respons\u00e1vel em distribuir as quotas de cada uma das entidades recebedoras, sendo: 60% (sessenta por cento) ao sindicato respectivo; 20% (vinte por cento) para a conta especial de emprego e sal\u00e1rio, administrada pela Uni\u00e3o Federal; 15% (quinze por cento) para a federa\u00e7\u00e3o pertinente e 5% (cinco por cento) \u00e0 confedera\u00e7\u00e3o correspondente.<\/p>\n<p>Assim, como pode ser observado, s\u00e3o v\u00e1rios os setores beneficiados com o pagamento da Contribui\u00e7\u00e3o Sindical. Agora, com a nova legisla\u00e7\u00e3o, todos devem se adaptar. As empresas devem acompanhar o desenvolvimento que as mudan\u00e7as trar\u00e3o para que possam decidir se far\u00e3o ou n\u00e3o os pagamentos. \u00c9 importante que tudo seja feito em conformidade com os trabalhos e benfeitorias realizadas pelas entidades que as representam.<\/p>\n<p><a href=\"https:\/\/www.conube.com.br\/?utm_source=blog&amp;utm_medium=cta&amp;utm_campaign=site-conheca-conube_v1\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-55849 size-full\" src=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2019\/12\/Site-Conheca-Conube_v1-1-2.png\" alt=\"como-definir-o-porte-da-empresa\" width=\"700\" height=\"330\" srcset=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2019\/12\/Site-Conheca-Conube_v1-1-2.png 700w, https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2019\/12\/Site-Conheca-Conube_v1-1-2-300x141.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p><strong>E ent\u00e3o, entendeu o que\u00a0\u00e9\u00a0Contribui\u00e7\u00e3o Sindical Patronal? O que achou do conte\u00fado? Deixe seus coment\u00e1rios!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe qual a import\u00e2ncia de conhecer o conceito de\u00a0Contribui\u00e7\u00e3o Sindical Patronal? No que o seu pagamento pode impactar sua empresa? Entenda tudo sobre essa contribui\u00e7\u00e3o e tamb\u00e9m descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 contribui\u00e7\u00e3o sindical patronal. O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? A Contribui\u00e7\u00e3o Sindical Patronal [&hellip;]<\/p>\n","protected":false},"author":145,"featured_media":56065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"content-type":""},"categories":[131],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Sou a obrigado a pagar?<\/title>\n<meta name=\"description\" content=\"Entenda tudo sobre essa contribui\u00e7\u00e3o e descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Sou a obrigado a pagar?\" \/>\n<meta property=\"og:description\" content=\"Entenda tudo sobre essa contribui\u00e7\u00e3o e descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da Conube - Contabilidade e empreendedorismo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/conube\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-13T21:27:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T19:55:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Capa-O-que-e-Contribuicao-Sindical-Patronal-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andressa Petronetto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@conubeweb\" \/>\n<meta name=\"twitter:site\" content=\"@conubeweb\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andressa Petronetto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\"},\"author\":{\"name\":\"Andressa Petronetto\",\"@id\":\"https:\/\/conube.com.br\/blog\/#\/schema\/person\/faf26c334e2bbbdd38dfe3d0654f6345\"},\"headline\":\"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Minha empresa \u00e9 obrigada a pagar?\",\"datePublished\":\"2018-04-13T21:27:29+00:00\",\"dateModified\":\"2025-01-28T19:55:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\"},\"wordCount\":1284,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\/\/conube.com.br\/blog\/#organization\"},\"articleSection\":[\"Recursos Humanos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\",\"url\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\",\"name\":\"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Sou a obrigado a pagar?\",\"isPartOf\":{\"@id\":\"https:\/\/conube.com.br\/blog\/#website\"},\"datePublished\":\"2018-04-13T21:27:29+00:00\",\"dateModified\":\"2025-01-28T19:55:18+00:00\",\"description\":\"Entenda tudo sobre essa contribui\u00e7\u00e3o e descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal.\",\"breadcrumb\":{\"@id\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/conube.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Minha empresa \u00e9 obrigada a pagar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conube.com.br\/blog\/#website\",\"url\":\"https:\/\/conube.com.br\/blog\/\",\"name\":\"Blog da Conube - Contabilidade e empreendedorismo\",\"description\":\"Fique por dentro de diversas novidades e dicas sobre neg\u00f3cios e contabilidade que ajudam na gest\u00e3o do seu neg\u00f3cio. Saiba mais.\",\"publisher\":{\"@id\":\"https:\/\/conube.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conube.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/conube.com.br\/blog\/#organization\",\"name\":\"Blog da Conube - Contabilidade e empreendedorismo\",\"url\":\"https:\/\/conube.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/conube.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2025\/10\/logo-conube.png\",\"contentUrl\":\"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2025\/10\/logo-conube.png\",\"width\":222,\"height\":61,\"caption\":\"Blog da Conube - Contabilidade e empreendedorismo\"},\"image\":{\"@id\":\"https:\/\/conube.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/conube\/\",\"https:\/\/twitter.com\/conubeweb\",\"https:\/\/www.instagram.com\/conubeweb\/\",\"https:\/\/www.linkedin.com\/company\/conube\",\"https:\/\/www.youtube.com\/user\/ContabilidadeOnline\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/conube.com.br\/blog\/#\/schema\/person\/faf26c334e2bbbdd38dfe3d0654f6345\",\"name\":\"Andressa Petronetto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/conube.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/caad64f92e52c1f72951dfe3aeb1d86d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/caad64f92e52c1f72951dfe3aeb1d86d?s=96&d=mm&r=g\",\"caption\":\"Andressa Petronetto\"},\"description\":\"Graduada em Direito, trabalhou na defesa dos direitos dos consumidores-Procon\/ES e no Controle Interno da Administra\u00e7\u00e3o P\u00fablica. Hoje atua na legaliza\u00e7\u00e3o de empresas da Conube Contabilidade Online.\",\"url\":\"https:\/\/conube.com.br\/blog\/author\/andressa-petronetto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Sou a obrigado a pagar?","description":"Entenda tudo sobre essa contribui\u00e7\u00e3o e descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Sou a obrigado a pagar?","og_description":"Entenda tudo sobre essa contribui\u00e7\u00e3o e descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal.","og_url":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/","og_site_name":"Blog da Conube - Contabilidade e empreendedorismo","article_publisher":"https:\/\/www.facebook.com\/conube\/","article_published_time":"2018-04-13T21:27:29+00:00","article_modified_time":"2025-01-28T19:55:18+00:00","og_image":[{"width":1280,"height":520,"url":"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2018\/04\/Capa-O-que-e-Contribuicao-Sindical-Patronal-1.png","type":"image\/png"}],"author":"Andressa Petronetto","twitter_card":"summary_large_image","twitter_creator":"@conubeweb","twitter_site":"@conubeweb","twitter_misc":{"Escrito por":"Andressa Petronetto","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#article","isPartOf":{"@id":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/"},"author":{"name":"Andressa Petronetto","@id":"https:\/\/conube.com.br\/blog\/#\/schema\/person\/faf26c334e2bbbdd38dfe3d0654f6345"},"headline":"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Minha empresa \u00e9 obrigada a pagar?","datePublished":"2018-04-13T21:27:29+00:00","dateModified":"2025-01-28T19:55:18+00:00","mainEntityOfPage":{"@id":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/"},"wordCount":1284,"commentCount":4,"publisher":{"@id":"https:\/\/conube.com.br\/blog\/#organization"},"articleSection":["Recursos Humanos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/","url":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/","name":"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Sou a obrigado a pagar?","isPartOf":{"@id":"https:\/\/conube.com.br\/blog\/#website"},"datePublished":"2018-04-13T21:27:29+00:00","dateModified":"2025-01-28T19:55:18+00:00","description":"Entenda tudo sobre essa contribui\u00e7\u00e3o e descubra o que mudou depois da nova Reforma Trabalhista. Comece aprendendo o que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal.","breadcrumb":{"@id":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/conube.com.br\/blog\/o-que-e-contribuicao-sindical-patronal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/conube.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 Contribui\u00e7\u00e3o Sindical Patronal? Minha empresa \u00e9 obrigada a pagar?"}]},{"@type":"WebSite","@id":"https:\/\/conube.com.br\/blog\/#website","url":"https:\/\/conube.com.br\/blog\/","name":"Blog da Conube - Contabilidade e empreendedorismo","description":"Fique por dentro de diversas novidades e dicas sobre neg\u00f3cios e contabilidade que ajudam na gest\u00e3o do seu neg\u00f3cio. Saiba mais.","publisher":{"@id":"https:\/\/conube.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conube.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/conube.com.br\/blog\/#organization","name":"Blog da Conube - Contabilidade e empreendedorismo","url":"https:\/\/conube.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/conube.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2025\/10\/logo-conube.png","contentUrl":"https:\/\/conube.com.br\/blog\/wp-content\/uploads\/2025\/10\/logo-conube.png","width":222,"height":61,"caption":"Blog da Conube - Contabilidade e empreendedorismo"},"image":{"@id":"https:\/\/conube.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/conube\/","https:\/\/twitter.com\/conubeweb","https:\/\/www.instagram.com\/conubeweb\/","https:\/\/www.linkedin.com\/company\/conube","https:\/\/www.youtube.com\/user\/ContabilidadeOnline"]},{"@type":"Person","@id":"https:\/\/conube.com.br\/blog\/#\/schema\/person\/faf26c334e2bbbdd38dfe3d0654f6345","name":"Andressa Petronetto","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/conube.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/caad64f92e52c1f72951dfe3aeb1d86d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/caad64f92e52c1f72951dfe3aeb1d86d?s=96&d=mm&r=g","caption":"Andressa Petronetto"},"description":"Graduada em Direito, trabalhou na defesa dos direitos dos consumidores-Procon\/ES e no Controle Interno da Administra\u00e7\u00e3o P\u00fablica. Hoje atua na legaliza\u00e7\u00e3o de empresas da Conube Contabilidade Online.","url":"https:\/\/conube.com.br\/blog\/author\/andressa-petronetto\/"}]}},"_links":{"self":[{"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/posts\/51701"}],"collection":[{"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/users\/145"}],"replies":[{"embeddable":true,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/comments?post=51701"}],"version-history":[{"count":4,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/posts\/51701\/revisions"}],"predecessor-version":[{"id":56064,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/posts\/51701\/revisions\/56064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/media\/56065"}],"wp:attachment":[{"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/media?parent=51701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/categories?post=51701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conube.com.br\/blog\/wp-json\/wp\/v2\/tags?post=51701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}